{"id":11029,"date":"2022-07-15T17:22:08","date_gmt":"2022-07-15T15:22:08","guid":{"rendered":"https:\/\/www.stpierre-bru.be\/brochure\/travel-vaccine-clinic\/"},"modified":"2022-07-15T17:22:08","modified_gmt":"2022-07-15T15:22:08","slug":"travel-vaccine-clinic","status":"publish","type":"brochure","link":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/","title":{"rendered":"Travel &amp; vaccine clinic"},"content":{"rendered":"","protected":false},"featured_media":50748,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"categories":[2103],"tags":[2246,2621,2252,2247,2245,2116,2248,2092,2117],"class_list":["post-11029","brochure","type-brochure","status-publish","has-post-thumbnail","hentry","category-infectieziekten","tag-advies-nl","tag-immunostart-nl","tag-muggen","tag-opkomende-ziekten-nl","tag-preventie-nl","tag-reizen","tag-reizigers-nl","tag-travel-vaccine-clinic-nl","tag-vaccin-nl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Travel &amp; vaccine clinic - CHU Saint-Pierre | UMC Sint-Pieter<\/title>\n<meta name=\"description\" content=\"Deze brochure geeft advies voor reizigers zoals de vaccinaties, de tropische geneeskunde, de opkomende ziekten, en andere.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel &amp; vaccine clinic - CHU Saint-Pierre | UMC Sint-Pieter\" \/>\n<meta property=\"og:description\" content=\"Deze brochure geeft advies voor reizigers zoals de vaccinaties, de tropische geneeskunde, de opkomende ziekten, en andere.\" \/>\n<meta property=\"og:site_name\" content=\"CHU Saint-Pierre | UMC Sint-Pieter\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.stpierre-bru.be\/wp-content\/uploads\/2022\/07\/T-V-coverNL.png?fit=576%2C851&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"576\" \/>\n\t<meta property=\"og:image:height\" content=\"851\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/brochure\\\/travel-vaccine-clinic\\\/\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/brochure\\\/travel-vaccine-clinic\\\/\",\"name\":\"Travel &amp; vaccine clinic - CHU Saint-Pierre | UMC Sint-Pieter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/brochure\\\/travel-vaccine-clinic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/brochure\\\/travel-vaccine-clinic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stpierre-bru.be\\\/app\\\/uploads\\\/2025\\\/02\\\/A5_brochure_TravelVaccineClinic_NL_050225.jpg\",\"datePublished\":\"2022-07-15T15:22:08+00:00\",\"description\":\"Deze brochure geeft advies voor reizigers zoals de vaccinaties, de tropische geneeskunde, de opkomende ziekten, en andere.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/brochure\\\/travel-vaccine-clinic\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/brochure\\\/travel-vaccine-clinic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/brochure\\\/travel-vaccine-clinic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/app\\\/uploads\\\/2025\\\/02\\\/A5_brochure_TravelVaccineClinic_NL_050225.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stpierre-bru.be\\\/app\\\/uploads\\\/2025\\\/02\\\/A5_brochure_TravelVaccineClinic_NL_050225.jpg\",\"width\":874,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/brochure\\\/travel-vaccine-clinic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brochures\",\"item\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nl\\\/brochure\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Travel &amp; vaccine clinic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#website\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/\",\"name\":\"CHU Saint-Pierre | UMC Sint-Pieter\",\"description\":\"Bienvenue\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stpierre-bru.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#organization\",\"name\":\"CHU Saint-Pierre | UMC Sint-Pieter\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo_chu_umc_0.png\",\"contentUrl\":\"https:\\\/\\\/www.stpierre-bru.be\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo_chu_umc_0.png\",\"width\":733,\"height\":281,\"caption\":\"CHU Saint-Pierre | UMC Sint-Pieter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel &amp; vaccine clinic - CHU Saint-Pierre | UMC Sint-Pieter","description":"Deze brochure geeft advies voor reizigers zoals de vaccinaties, de tropische geneeskunde, de opkomende ziekten, en andere.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/","og_locale":"nl_NL","og_type":"article","og_title":"Travel &amp; vaccine clinic - CHU Saint-Pierre | UMC Sint-Pieter","og_description":"Deze brochure geeft advies voor reizigers zoals de vaccinaties, de tropische geneeskunde, de opkomende ziekten, en andere.","og_site_name":"CHU Saint-Pierre | UMC Sint-Pieter","og_image":[{"width":576,"height":851,"url":"https:\/\/i0.wp.com\/www.stpierre-bru.be\/wp-content\/uploads\/2022\/07\/T-V-coverNL.png?fit=576%2C851&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/","url":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/","name":"Travel &amp; vaccine clinic - CHU Saint-Pierre | UMC Sint-Pieter","isPartOf":{"@id":"https:\/\/www.stpierre-bru.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/#primaryimage"},"image":{"@id":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2025\/02\/A5_brochure_TravelVaccineClinic_NL_050225.jpg","datePublished":"2022-07-15T15:22:08+00:00","description":"Deze brochure geeft advies voor reizigers zoals de vaccinaties, de tropische geneeskunde, de opkomende ziekten, en andere.","breadcrumb":{"@id":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/#primaryimage","url":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2025\/02\/A5_brochure_TravelVaccineClinic_NL_050225.jpg","contentUrl":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2025\/02\/A5_brochure_TravelVaccineClinic_NL_050225.jpg","width":874,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/travel-vaccine-clinic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stpierre-bru.be\/nl\/home\/"},{"@type":"ListItem","position":2,"name":"Brochures","item":"https:\/\/www.stpierre-bru.be\/nl\/brochure\/"},{"@type":"ListItem","position":3,"name":"Travel &amp; vaccine clinic"}]},{"@type":"WebSite","@id":"https:\/\/www.stpierre-bru.be\/#website","url":"https:\/\/www.stpierre-bru.be\/","name":"CHU Saint-Pierre | UMC Sint-Pieter","description":"Bienvenue","publisher":{"@id":"https:\/\/www.stpierre-bru.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stpierre-bru.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.stpierre-bru.be\/#organization","name":"CHU Saint-Pierre | UMC Sint-Pieter","url":"https:\/\/www.stpierre-bru.be\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.stpierre-bru.be\/#\/schema\/logo\/image\/","url":"https:\/\/www.stpierre-bru.be\/wp-content\/uploads\/2021\/06\/Logo_chu_umc_0.png","contentUrl":"https:\/\/www.stpierre-bru.be\/wp-content\/uploads\/2021\/06\/Logo_chu_umc_0.png","width":733,"height":281,"caption":"CHU Saint-Pierre | UMC Sint-Pieter"},"image":{"@id":"https:\/\/www.stpierre-bru.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.stpierre-bru.be\/nl\/wp-json\/wp\/v2\/brochure\/11029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stpierre-bru.be\/nl\/wp-json\/wp\/v2\/brochure"}],"about":[{"href":"https:\/\/www.stpierre-bru.be\/nl\/wp-json\/wp\/v2\/types\/brochure"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/nl\/wp-json\/wp\/v2\/media\/50748"}],"wp:attachment":[{"href":"https:\/\/www.stpierre-bru.be\/nl\/wp-json\/wp\/v2\/media?parent=11029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/nl\/wp-json\/wp\/v2\/categories?post=11029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/nl\/wp-json\/wp\/v2\/tags?post=11029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}