{"id":969,"date":"2021-11-11T23:16:54","date_gmt":"2021-11-11T22:16:54","guid":{"rendered":"http:\/\/10.14.1.26\/website\/specialite\/oncologie-gynecologie\/"},"modified":"2025-10-17T15:37:35","modified_gmt":"2025-10-17T13:37:35","slug":"oncologie-gynecologie","status":"publish","type":"service","link":"https:\/\/www.stpierre-bru.be\/en\/service\/cancerologie\/oncologie-gynecologie\/","title":{"rendered":"Cancers gyn\u00e9cologiques"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Chaque patiente fait l\u2019objet d\u2019une <span style=\"color: #000000;\">prise<\/span> en charge continue par notre \u00e9quipe pluridisciplinaire pour le diagnostic, le traitement et le suivi des <strong>cancers gyn\u00e9cologiques pelviens<\/strong>.<\/p>\n<p>Les tumeurs les plus fr\u00e9quentes sont le cancer de l\u2019endom\u00e8tre (corps de l\u2019ut\u00e9rus), de l\u2019ovaire et du col de l\u2019ut\u00e9rus.<\/p>\n<p>Les tumeurs plus rares comme les cancers de la vulve et du vagin sont aussi prises en charge dans notre unit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong><span style=\"color: #33cccc;\">Equipe multidisciplinaire<\/span><\/strong><\/h3>\n<p>Notre \u00e9quipe est compos\u00e9e de gyn\u00e9co-oncologues (reconnus pour leur sp\u00e9cialisation en canc\u00e9rologie gyn\u00e9cologique), d\u2019oncologues m\u00e9dicaux, de <a href=\"https:\/\/www.bordet.be\/en\/alex-de-caluwe\">radioth\u00e9rapeutes<\/a>, <a href=\"https:\/\/www.bordet.be\/en\/nicolas-sirtaine\">d\u2019anatomo-pathologistes<\/a>,\u00a0de radiologues, de sp\u00e9cialistes en m\u00e9decine nucl\u00e9aire, d\u2019infirmi\u00e8res coordinatrices et d\u2019onco-psychologues.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong><span style=\"color: #33cccc;\">Mini-invasive<\/span><\/strong><\/h3>\n<p>La clinique de gyn\u00e9co-oncologie du CHU Saint Pierre est \u00e0 la pointe des traitements chirurgicaux, notamment en chirurgie dite <strong>mini-invasive<\/strong> (<strong>laparoscopie<\/strong>, <strong>endoscopie interventionnelle<\/strong>), qui permet de diminuer les effets secondaires de la chirurgie et am\u00e9liorer la qualit\u00e9 de vie des patientes.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #33cccc;\"><strong>Recherche clinique<\/strong><\/span><\/h3>\n<p>Notre clinique participe en outre \u00e0 de nombreuses \u00e9tudes cliniques au sein du <strong><em>Belgian Gynecologic Oncology Group<\/em><\/strong><em> (BGOG)<\/em>, qui contribuent sans cesse \u00e0 l\u2019am\u00e9lioration de la prise en charge des patientes et de leur maladie.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong><span style=\"color: #33cccc;\">Cancer et fertilit\u00e9 \/<a href=\"https:\/\/www.stpierre-bru.be\/fr\/services-medicaux\/gynecologie-obstetrique\/pma-procreation-medicalement-assistee-fertilite\/onco-fertilite\" style=\"color: #33cccc;\">Oncofertilit\u00e9<\/a><\/span><\/strong><\/h3>\n<p>Notre service est \u00e0 vos c\u00f4t\u00e9s pour contribuer \u00e0 votre qualit\u00e9 de vie. Nous vous donnerons\u00a0 toutes les informations n\u00e9cessaires sur les moyens de pr\u00e9server votre fertilit\u00e9 d\u00e8s l\u2019annonce \u00a0du diagnostic de cancer.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre clinique <strong>de gyn&eacute;co-oncologie<\/strong> offre une prise en charge multidisciplinaire des <strong>cancers gyn&eacute;cologiques<\/strong> les plus fr&eacute;quents (cancer de l&rsquo;<strong>endom&egrave;tre<\/strong>, des <strong>ovaires<\/strong>, du <strong>col de l&rsquo;ut&eacute;rus<\/strong>) mais aussi plus rares (cancers de la <strong>vulve<\/strong>, du <strong>vagin<\/strong>). &nbsp;<\/p>\n","protected":false},"featured_media":4037,"parent":818,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"Chaque patiente fait l\u2019objet d\u2019une prise en charge continue par notre \u00e9quipe pluridisciplinaire pour le diagnostic, le traitement et le suivi des <strong>cancers gyn\u00e9cologiques pelviens<\/strong>.\r\n\r\nLes tumeurs les plus fr\u00e9quentes sont le cancer de l\u2019endom\u00e8tre (corps de l\u2019ut\u00e9rus), de l\u2019ovaire et du col de l\u2019ut\u00e9rus.\r\n\r\nLes tumeurs plus rares comme les cancers de la vulve et du vagin sont aussi prises en charge dans notre unit\u00e9.\r\n<h2>Equipe multidisciplinaire<\/h2>\r\nNotre \u00e9quipe est compos\u00e9e de gyn\u00e9co-oncologues (reconnus pour leur sp\u00e9cialisation en canc\u00e9rologie gyn\u00e9cologique), d\u2019oncologues m\u00e9dicaux, de <a href=\"https:\/\/www.bordet.be\/en\/alex-de-caluwe\">radioth\u00e9rapeutes<\/a>, <a href=\"https:\/\/www.bordet.be\/en\/nicolas-sirtaine\">d\u2019anatomo-pathologistes<\/a>,\u00a0de radiologues, de sp\u00e9cialistes en m\u00e9decine nucl\u00e9aire, d\u2019infirmi\u00e8res coordinatrices et d\u2019onco-psychologues.\r\n<h2>Mini-invasive<\/h2>\r\nLa clinique de gyn\u00e9co-oncologie du CHU Saint Pierre est \u00e0 la pointe des traitements chirurgicaux, notamment en chirurgie dite <strong>mini-invasive<\/strong> (<strong>laparoscopie<\/strong>, <strong>endoscopie interventionnelle<\/strong>), qui permet de diminuer les effets secondaires de la chirurgie et am\u00e9liorer la qualit\u00e9 de vie des patientes.\r\n<h2>Recherche clinique<\/h2>\r\nNotre clinique participe en outre \u00e0 de nombreuses \u00e9tudes cliniques au sein du <strong><em>Belgian Gynecologic Oncology Group<\/em><\/strong><em> (BGOG)<\/em>, qui contribuent sans cesse \u00e0 l\u2019am\u00e9lioration de la prise en charge des patientes et de leur maladie.\r\n<h2>Cancer et fertilit\u00e9 \/<a href=\"https:\/\/www.stpierre-bru.be\/fr\/services-medicaux\/gynecologie-obstetrique\/pma-procreation-medicalement-assistee-fertilite\/onco-fertilite\">Oncofertilit\u00e9<\/a><\/h2>\r\nNotre service est \u00e0 vos c\u00f4t\u00e9s pour contribuer \u00e0 votre qualit\u00e9 de vie. Nous vous donnerons\u00a0 toutes les informations n\u00e9cessaires sur les moyens de pr\u00e9server votre fertilit\u00e9 d\u00e8s l\u2019annonce \u00a0du diagnostic de cancer.","_et_gb_content_width":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"categories":[1853,44],"tags":[84,145,143,147,148,144,142,86],"class_list":["post-969","service","type-service","status-publish","has-post-thumbnail","hentry","category-cancerologie","category-specialite","tag-bruxelles","tag-cancer-col-de-luterus","tag-cancer-de-luterus","tag-cancer-de-la-vulve","tag-cancer-du-vagin","tag-cancers-de-lovaire","tag-cancers-gynecologiques","tag-gynecologie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cancers gyn\u00e9cologiques - CHU Saint-Pierre | UMC Sint-Pieter<\/title>\n<meta name=\"description\" content=\"Les tumeurs les plus fr\u00e9quentes sont le cancer de l\u2019endom\u00e8tre (corps de l\u2019ut\u00e9rus), de l\u2019ovaire et du col de l\u2019ut\u00e9rus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cancers gyn\u00e9cologiques - CHU Saint-Pierre | UMC Sint-Pieter\" \/>\n<meta property=\"og:description\" content=\"Les tumeurs les plus fr\u00e9quentes sont le cancer de l\u2019endom\u00e8tre (corps de l\u2019ut\u00e9rus), de l\u2019ovaire et du col de l\u2019ut\u00e9rus.\" \/>\n<meta property=\"og:site_name\" content=\"CHU Saint-Pierre | UMC Sint-Pieter\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T13:37:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stpierre-bru.be\/app\/uploads\/2021\/11\/Gynecologie_service_bruxelles.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/cancerologie\\\/oncologie-gynecologie\\\/\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/cancerologie\\\/oncologie-gynecologie\\\/\",\"name\":\"Cancers gyn\u00e9cologiques - CHU Saint-Pierre | UMC Sint-Pieter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/cancerologie\\\/oncologie-gynecologie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/cancerologie\\\/oncologie-gynecologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stpierre-bru.be\\\/app\\\/uploads\\\/2021\\\/11\\\/Gynecologie_service_bruxelles.png\",\"datePublished\":\"2021-11-11T22:16:54+00:00\",\"dateModified\":\"2025-10-17T13:37:35+00:00\",\"description\":\"Les tumeurs les plus fr\u00e9quentes sont le cancer de l\u2019endom\u00e8tre (corps de l\u2019ut\u00e9rus), de l\u2019ovaire et du col de l\u2019ut\u00e9rus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/cancerologie\\\/oncologie-gynecologie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/cancerologie\\\/oncologie-gynecologie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/cancerologie\\\/oncologie-gynecologie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/app\\\/uploads\\\/2021\\\/11\\\/Gynecologie_service_bruxelles.png\",\"contentUrl\":\"https:\\\/\\\/www.stpierre-bru.be\\\/app\\\/uploads\\\/2021\\\/11\\\/Gynecologie_service_bruxelles.png\",\"width\":850,\"height\":567,\"caption\":\"Gyn\u00e9cologie g\u00e9n\u00e9rale m\u00e9nopause grossesse sant\u00e9 f\u00e9minine mutilations g\u00e9nitales violence sexuelles contraception accouchement\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/cancerologie\\\/oncologie-gynecologie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stpierre-bru.be\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nos-services-de-consultation\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oncologie\",\"item\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/cancerologie\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cancers gyn\u00e9cologiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#website\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/\",\"name\":\"CHU Saint-Pierre | UMC Sint-Pieter\",\"description\":\"Bienvenue\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stpierre-bru.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#organization\",\"name\":\"CHU Saint-Pierre | UMC Sint-Pieter\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo_chu_umc_0.png\",\"contentUrl\":\"https:\\\/\\\/www.stpierre-bru.be\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo_chu_umc_0.png\",\"width\":733,\"height\":281,\"caption\":\"CHU Saint-Pierre | UMC Sint-Pieter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cancers gyn\u00e9cologiques - CHU Saint-Pierre | UMC Sint-Pieter","description":"Les tumeurs les plus fr\u00e9quentes sont le cancer de l\u2019endom\u00e8tre (corps de l\u2019ut\u00e9rus), de l\u2019ovaire et du col de l\u2019ut\u00e9rus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/","og_locale":"en_US","og_type":"article","og_title":"Cancers gyn\u00e9cologiques - CHU Saint-Pierre | UMC Sint-Pieter","og_description":"Les tumeurs les plus fr\u00e9quentes sont le cancer de l\u2019endom\u00e8tre (corps de l\u2019ut\u00e9rus), de l\u2019ovaire et du col de l\u2019ut\u00e9rus.","og_site_name":"CHU Saint-Pierre | UMC Sint-Pieter","article_modified_time":"2025-10-17T13:37:35+00:00","og_image":[{"width":850,"height":567,"url":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2021\/11\/Gynecologie_service_bruxelles.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/","url":"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/","name":"Cancers gyn\u00e9cologiques - CHU Saint-Pierre | UMC Sint-Pieter","isPartOf":{"@id":"https:\/\/www.stpierre-bru.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/#primaryimage"},"image":{"@id":"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2021\/11\/Gynecologie_service_bruxelles.png","datePublished":"2021-11-11T22:16:54+00:00","dateModified":"2025-10-17T13:37:35+00:00","description":"Les tumeurs les plus fr\u00e9quentes sont le cancer de l\u2019endom\u00e8tre (corps de l\u2019ut\u00e9rus), de l\u2019ovaire et du col de l\u2019ut\u00e9rus.","breadcrumb":{"@id":"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/#primaryimage","url":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2021\/11\/Gynecologie_service_bruxelles.png","contentUrl":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2021\/11\/Gynecologie_service_bruxelles.png","width":850,"height":567,"caption":"Gyn\u00e9cologie g\u00e9n\u00e9rale m\u00e9nopause grossesse sant\u00e9 f\u00e9minine mutilations g\u00e9nitales violence sexuelles contraception accouchement"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/oncologie-gynecologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stpierre-bru.be\/en\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/www.stpierre-bru.be\/nos-services-de-consultation\/"},{"@type":"ListItem","position":3,"name":"Oncologie","item":"https:\/\/www.stpierre-bru.be\/service\/cancerologie\/"},{"@type":"ListItem","position":4,"name":"Cancers gyn\u00e9cologiques"}]},{"@type":"WebSite","@id":"https:\/\/www.stpierre-bru.be\/#website","url":"https:\/\/www.stpierre-bru.be\/","name":"CHU Saint-Pierre | UMC Sint-Pieter","description":"Bienvenue","publisher":{"@id":"https:\/\/www.stpierre-bru.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stpierre-bru.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.stpierre-bru.be\/#organization","name":"CHU Saint-Pierre | UMC Sint-Pieter","url":"https:\/\/www.stpierre-bru.be\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.stpierre-bru.be\/#\/schema\/logo\/image\/","url":"https:\/\/www.stpierre-bru.be\/wp-content\/uploads\/2021\/06\/Logo_chu_umc_0.png","contentUrl":"https:\/\/www.stpierre-bru.be\/wp-content\/uploads\/2021\/06\/Logo_chu_umc_0.png","width":733,"height":281,"caption":"CHU Saint-Pierre | UMC Sint-Pieter"},"image":{"@id":"https:\/\/www.stpierre-bru.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/service\/969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/types\/service"}],"up":[{"embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/service\/818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/media\/4037"}],"wp:attachment":[{"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/media?parent=969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/categories?post=969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/tags?post=969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}