{"id":1012,"date":"2021-11-14T22:25:10","date_gmt":"2021-11-14T21:25:10","guid":{"rendered":"http:\/\/10.14.1.26\/website\/specialite\/chirurgie-de-la-colonne-vertebrale\/"},"modified":"2022-03-27T21:55:48","modified_gmt":"2022-03-27T19:55:48","slug":"chirurgie-de-la-colonne-vertebrale","status":"publish","type":"service","link":"https:\/\/www.stpierre-bru.be\/en\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/","title":{"rendered":"Chirurgie de la colonne vert\u00e9brale"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.22&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Dans la plupart des cas, il s\u2019agit de blessures du disque intervert\u00e9bral, li\u00e9es \u00e0 son vieillissement naturel et ne repr\u00e9sente pas une maladie en tant que telle. La prise en charge de ces maux de dos chroniques est souvent complexe et n\u00e9cessite l\u2019implication de divers intervenants pour amener un soulagement au patient.<\/p>\n<p>La clinique du dos du CHU Saint-Pierre fait partie int\u00e9grante du service d\u2019orthop\u00e9die et se compose de kin\u00e9sith\u00e9rapeutes, ost\u00e9opathes, sophrologues, acupuncteurs, m\u00e9decin physique et chirurgiens. Une approche pluridisciplinaire permet ainsi d\u2019apporter une prise en charge personnalis\u00e9e pour chaque cas.<\/p>\n<p>L\u2019\u00e9quipe d\u2019orthop\u00e9die du CHU Saint-Pierre comprend plusieurs chirurgiens sp\u00e9cialis\u00e9s dans la chirurgie de la colonne. Parmi ceux-ci, il y a des membres de soci\u00e9t\u00e9s nationales et internationales de chirurgie de la colonne, auteurs de divers travaux scientifiques.<\/p>\n<p>Toutes les pathologies chirurgicales touchant la colonne sont prises en charge dans notre service qui travaille \u00e9galement en \u00e9troite collaboration avec le service de neurochirurgie et nous utilisons les techniques les plus modernes afin de garantir une prise en charge optimale.<\/p>\n<p>Outre les cas de tumeurs ou de fracture de la colonne, heureusement plus rares, les pathologies les plus souvent trait\u00e9es de fa\u00e7on chirurgicale sont le canal \u00e9troit lombaire, la hernie discale cervicale ou lombaire, la lombalgie primaire r\u00e9sistante au traitement m\u00e9dical.<\/p>\n<p>[\/et_pb_text][et_pb_accordion icon_color=&#8221;#00B9B4&#8243; _builder_version=&#8221;4.14.7&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;|-198px||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; open_toggle_text_color=&#8221;#00B9B4&#8243; toggle_text_color=&#8221;#00B9B4&#8243; toggle_font=&#8221;|600|||||||&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_accordion_item title=&#8221;G\u00e9n\u00e9ralit\u00e9s&#8221; open=&#8221;on&#8221; _builder_version=&#8221;4.14.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>La colonne vert\u00e9brale ou rachis se d\u00e9compose en 4 zones, de haut en bas, en colonne cervicale (7 vert\u00e8bres), thoracique (12 vert\u00e8bres), lombaire (5 vert\u00e8bres) et sacr\u00e9e (5 vert\u00e8bres soud\u00e9es). Elle se termine par le coccyx. Dans le plan frontal, la colonne est rectiligne mais de profil, elle forme un S allong\u00e9. On parle de lordose cervicale, cyphose dorsale et lordose lombaire. Ses courbures sont physiologiques quand elles restent dans certaines limites et sont telles que la t\u00eate se situe au-dessus du bassin. On parle de colonne bien \u00e9quilibr\u00e9e.<\/p>\n<p>La colonne a une fonction de soutien du corps mais \u00e9galement de protection de la moelle.<\/p>\n<p>Au niveau de chaque vert\u00e8bre, deux nerfs sortent de la colonne par les trous de conjugaison ou foramen, un \u00e0 gauche et un \u00e0 droite, pour innerver les muscles ou donner la sensibilit\u00e9 dans certains territoires de la peau. Chaque nerf a un territoire bien pr\u00e9cis. Les nerfs sortants au niveau des trois derni\u00e8res vert\u00e8bres lombaires se regroupent en un gros nerf, le nerf sciatique, puis se s\u00e9parent plus bas dans la jambe pour rejoindre leur territoire cutan\u00e9 sp\u00e9cifique. Par exemple, le nerf sortant entre la cinqui\u00e8me vert\u00e8bre lombaire et le sacrum, va donner la sensibilit\u00e9 au gros orteil. S\u2019il est bless\u00e9 lorsqu&#8217;il sort de la colonne, comme dans le cas d&#8217;une hernie discale, le patient aura mal au gros orteil. Ceci permet de diagnostiquer facilement par le seul interrogatoire du patient, l&#8217;endroit o\u00f9 a pu se faire la hernie discale.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Le canal lombaire \u00e9troit&#8221; _builder_version=&#8221;4.14.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; open=&#8221;off&#8221;]<\/p>\n<p>\u00c9tant li\u00e9e au remaniement de la colonne vert\u00e9brale avec l\u2019\u00e2ge et au vu de l\u2019augmentation de l\u2019esp\u00e9rance de vie, cette affection est de plus en plus fr\u00e9quente et touche des patients principalement de 70, 80 voire 90 ans. Il s\u2019agit de la diminution du calibre du canal rachidien. Dans ce canal, passe la moelle \u00e9pini\u00e8re dans les r\u00e9gions cervicale et dorsale. Au niveau de la colonne lombaire on y retrouve le sac dural qui contient les racines nerveuses qui donneront l\u2019innervation dans les jambes. La diminution du diam\u00e8tre canalaire est la plupart du temps une cons\u00e9quence du vieillissement de la colonne vert\u00e9brale. Il y a d\u2019une part le vieillissement des disques intervert\u00e9braux qui s\u2019\u00e9crasent et viennent faire une protrusion dans le canal rachidien et d\u2019autre part l\u2019arthrose des articulations qui les d\u00e9forment, les rendant de plus en plus volumineuses. La conjonction de ces deux ph\u00e9nom\u00e8nes entra\u00eene une compression du sac dural et par l\u00e0 m\u00eame de l\u2019ensemble des nerfs.<\/p>\n<p>Canal normal \u00a0 \u00a0 \u00a0 \u00a0<img decoding=\"async\" alt=\"\" height=\"226\" src=\"http:\/\/www.stpierre-bru.be\/images\/dos\/3.jpg\" \/>\u00a0canal \u00e9troit<\/p>\n<p>Les plaintes d\u00e9crites par un patient pr\u00e9sentant un canal lombaire \u00e9troit sont assez typiques. Outre les douleurs lombaires li\u00e9es aux ph\u00e9nom\u00e8nes d\u2019arthrose, le patient ressentira surtout des douleurs dans les cuisses et dans les jambes apparaissant \u00e0 la marche. La douleur apparait typiquement apr\u00e8s une certaine distance de marche l\u2019obligeant \u00e0 s\u2019arr\u00eater et \u00e0 s\u2019asseoir pour que la douleur s\u2019estompe. Apr\u00e8s quelques minutes, il peut reprendre son chemin mais apr\u00e8s la m\u00eame distance de marche, les douleurs r\u00e9appara\u00eetront l\u2019obligeant une nouvelle fois \u00e0 s\u2019arr\u00eater.<\/p>\n<p>Cette affection \u00e9volue lentement, ne repr\u00e9sente pas un danger mais devient g\u00eanante pour le patient qui voit sa distance de marche se r\u00e9duire avec le temps.<\/p>\n<p>La question souvent pos\u00e9e est de savoir s\u2019il faut op\u00e9rer un canal \u00e9troit. Il est rare que le patient pr\u00e9sente des troubles neurologiques graves \u00e9voluant rapidement. C\u2019est pour cela, que l\u2019op\u00e9ration n\u2019est quasi jamais urgente et que l\u2019on peut se permettre dans un premier temps de proposer des traitements m\u00e9dicaux, kin\u00e9sith\u00e9rapie voire m\u00eame des p\u00e9ridurales pour soulager le patient. En cas d\u2019\u00e9chec de ces traitements et de g\u00eanes suffisantes entra\u00eenant une d\u00e9t\u00e9rioration de la qualit\u00e9 de vie, une intervention peut \u00eatre propos\u00e9e. Bien s\u00fbr, en cas de perte de force, de sensibilit\u00e9 ou de contr\u00f4le des sphincters, l\u2019intervention s\u2019av\u00e8re urgente.<\/p>\n<p>La peur du patient est souvent le risque de paralysie lors d\u2019une intervention. Les complications possibles de l\u2019intervention vous seront expliqu\u00e9es par votre chirurgien lors de la consultation. Bien que le risque z\u00e9ro n\u2019existe pas, le but de l\u2019intervention \u00e9tant de redonner de l\u2019espace aux structures nerveuses, tout doit aller vers une situation en am\u00e9liorant la situation neurologique du patient. L\u2019intervention se fait par une incision dans le dos et consiste \u00e0 \u00ab gratter \u00bb l\u2019os pour redonner suffisamment d\u2019espace aux structures nerveuses. Parfois, on peut associer une arthrod\u00e8se c\u2019est-\u00e0-dire une fusion des vert\u00e8bres \u00e0 l\u2019aide de vis si une instabilit\u00e9 des vert\u00e8bres est mise en \u00e9vidence. Cet ajout de vis a tr\u00e8s peu de cons\u00e9quences sur la mobilit\u00e9 qui est d\u00e9j\u00e0 fort diminu\u00e9e dans une colonne vert\u00e9brale atteinte d\u2019un canal \u00e9troit.<\/p>\n<p>Apr\u00e8s l\u2019intervention, le patient est alit\u00e9 parfois 24 heures puis peut marcher avec l\u2019aide d\u2019un kin\u00e9sith\u00e9rapeute. La dur\u00e9e moyenne d\u2019hospitalisation est de cinq jours. G\u00e9n\u00e9ralement, le patient est apte \u00e0 retourner \u00e0 son domicile apr\u00e8s ce d\u00e9lai. S\u2019il est isol\u00e9 et pourrait pr\u00e9senter des difficult\u00e9s pour son retour \u00e0 domicile, un s\u00e9jour en revalidation est toujours envisageable.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;La hernie discale&#8221; _builder_version=&#8221;4.14.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; open=&#8221;off&#8221;]<\/p>\n<p>Le disque vert\u00e9bral est compos\u00e9 de fibres de collag\u00e8ne concentriques autour du nuclleus pulposus. D\u00e8s 25 ans, des l\u00e9sions de ces fibres peuvent appara\u00eetre lors d&#8217;effort, comme soulever une charge, souvent pour des gestes de la vie courante. Des d\u00e9chirures surviennent entra\u00eenant la douleur. On parle de lumbago ou de lombalgie quand la douleur reste localis\u00e9e \u00e0 la colonne lombaire, cervicalgie au niveau cervical.<\/p>\n<p>Si la d\u00e9chirure est plus importante, le contenu du disque, le nucleus pulposus, peut s&#8217;\u00e9chapper dans le canal rachidien et cr\u00e9\u00e9 une hernie discale. La hernie peut \u00eatre centrale et comprimer le sac dural, ou, lat\u00e9rale et comprimer les racines. Il s&#8217;ensuit une douleur \u00e9lective dans un territoire de la jambe sp\u00e9cifique du nerf l\u00e9s\u00e9. On parle de sciatalgie pouvant \u00eatre associ\u00e9e \u00e0 une perte de sensibilit\u00e9 voire une paralysie.<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"http:\/\/www.stpierre-bru.be\/images\/dos\/4.jpg\" \/>Hernie lat\u00e9rale entra\u00eenant une compression de la racine nerveuse.<\/p>\n<p>Dans 80 % des cas, le traitement de la hernie discale ne n\u00e9cessite pas d\u2019op\u00e9ration. En cas d\u2019 hernie discale non paralysante, c\u2019est-\u00e0-dire n\u2019entra\u00eenant pas de troubles neurologiques graves, dans un premier temps, on commence toujours par un traitement conservateur par repos, anti-inflammatoires et relaxant musculaire. On peut \u00e9galement r\u00e9aliser une p\u00e9ridurale th\u00e9rapeutique. Il s&#8217;agit d&#8217;injecter de la cortisone localement afin de diminuer l&#8217;inflammation due \u00e0 la hernie. En cas d&#8217;\u00e9chec du traitement conservateur, on peut avoir recours \u00e0 la chirurgie, surtout lors de douleurs invalidantes. En cas de hernie discale paralysante ou s\u2019accompagnant d\u2019une anesth\u00e9sie, on a toujours recours \u00e0 une intervention chirurgicale en urgence.<\/p>\n<p>Le but de l\u2019intervention est d\u2019enlever la hernie et de cureter le disque pour \u00e9viter une r\u00e9cidive. Au niveau lombaire, le chirurgien incisera dans le dos en regard du disque ab\u00eem\u00e9. Gr\u00e2ce \u00e0 des instruments adapt\u00e9s, nous pouvons par microchirurgie r\u00e9aliser des incisions de moins de trois centim\u00e8tres pour aborder le disque malade. En \u00e9cartant prudemment le sac dural et la racine nerveuse,\u00a0 le chirurgien a acc\u00e8s \u00e0 la hernie et peut l\u2019\u00f4ter.<\/p>\n<p>Avec ce type d\u2019intervention, le patient peut g\u00e9n\u00e9ralement se lever le matin et sortir au deuxi\u00e8me ou troisi\u00e8me jour postop\u00e9ratoire.<\/p>\n<p>La hernie discale peut \u00e9galement \u00eatre pr\u00e9sente au niveau de la colonne cervicale. \u00c0 ce moment, le patient peut ressentir outre une douleur dans le cou, une douleur irradiante jusque dans les doigts. Les indications op\u00e9ratoires restent les m\u00eames que pour la r\u00e9gion lombaire. Dans la majorit\u00e9 des cas, le traitement est conservateur. Le patient b\u00e9n\u00e9ficie d\u2019anti-inflammatoires, de relaxants musculaires. Une p\u00e9ridurale cervicale peut \u00e9galement \u00eatre r\u00e9alis\u00e9e dans le cas de douleurs plus fortes. Le port d\u2019une minerve permet de mettre la r\u00e9gion cervicale au repos.\u00a0 L\u2019intervention est requise pour les douleurs invalidantes ne r\u00e9pondant pas au traitement classique ou en cas de d\u00e9ficit neurologique.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Arthrose lombaire et discopathies d\u00e9g\u00e9n\u00e9ratives&#8221; _builder_version=&#8221;4.14.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; open=&#8221;off&#8221;]<\/p>\n<p>L&#8217;arthrose de la colonne lombaire touche le plus fr\u00e9quemment les vert\u00e8bres L4, L5 et S1.\u00a0 Les douleurs occasionn\u00e9es par l&#8217;arthrose s&#8217;appellent des lombalgies.\u00a0 Elles sont dues \u00e0 l&#8217;usure du cartilage situ\u00e9 sur les facettes articulaires des vert\u00e8bres ou \u00e0 l\u2019usure des disques intervert\u00e9braux. On parlera dans ce dernier cas de discopathie.<\/p>\n<p>Le traitement sera m\u00e9dical mais se fera \u00e9galement via le repos, la kin\u00e9sith\u00e9rapie, l\u2019ost\u00e9opathie, l\u2019acupuncture, la physioth\u00e9rapie parfois m\u00eame par le psychologue en cas de douleur chronique associ\u00e9e \u00e0 un stress ou par un anesth\u00e9siste pour des d\u00e9sensibilisations. En cas de douleurs non soulag\u00e9es par le traitement m\u00e9dical, un blocage de deux ou plusieurs vert\u00e8bres par\u00a0 arthrod\u00e8se peut \u00eatre envisag\u00e9.\u00a0 Celui-ci se fait \u00e0 l&#8217;aide de plaques et de vis fixant les vert\u00e8bres malades entre elles.<\/p>\n<p>Cette intervention doit cependant rester exceptionnelle. En effet bon nombre de patients garde des douleurs apr\u00e8s l\u2019op\u00e9ration et on estime que seulement 70 % sont soulag\u00e9s apr\u00e8s la chirurgie et que seuls 20 \u00e0 30 % n\u2019ont plus de douleur. Ceci veut \u00e9galement dire que 30 % des patients ont gard\u00e9 des douleurs similaires voire plus importantes apr\u00e8s l\u2019intervention. On r\u00e9serve donc la chirurgie lorsqu\u2019 aucun autre traitement n\u2019a pu soulager le patient et que la douleur reste fortement invalidante, entravant la qualit\u00e9 de vie du patient.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;La scoliose&#8221; _builder_version=&#8221;4.14.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; open=&#8221;off&#8221;]<\/p>\n<section class=\"section section--white section-contents\">\n<div class=\"typeset  first-letter\">\n<p>Parmi les d\u00e9formations de la colonne vert\u00e9brale, la plus connue touchant l\u2019enfant est la scoliose. C\u2019est une d\u00e9formation compliqu\u00e9e de la colonne qui lui donne de face un aspect de S allong\u00e9. La d\u00e9viation peut se situer n&#8217;importe o\u00f9 sur la colonne. On parle de scoliose thoracique, thoraco-lombaire ou lombaire en fonction de l&#8217;endroit de la d\u00e9viation. Quand la maladie est situ\u00e9e au niveau thoracique et est tr\u00e8s \u00e9volu\u00e9e, les vert\u00e8bres qui pivotent, repoussent vers l&#8217;arri\u00e8re les c\u00f4tes situ\u00e9es du cot\u00e9 convexe de la courbure cr\u00e9ant une bosse ou une gibbosit\u00e9, qui se voit encore mieux lorsque le sujet se penche en avant.\u00a0<\/p>\n<p>La scoliose vraie est une d\u00e9formation irr\u00e9ductible et ne doit pas \u00eatre confondue avec une attitude scoliotique qui peut \u00eatre due \u00e0 un mauvais maintien d\u2019un patient debout, ou une scoliose compensatoire qui est une d\u00e9viation li\u00e9e \u00e0 une diff\u00e9rence de longueur de membres. Ces deux scolioses disparaissent en position couch\u00e9e.<\/p>\n<p>Devant une scoliose irr\u00e9ductible, on recherche toujours une cause neurologique ou cong\u00e9nitale mais dans plus de 70% des cas aucune cause ne sera retrouv\u00e9e. On parle alors de scoliose idiopathique. La scoliose idiopathique se rencontre 7 fois plus souvent chez les filles et peut appara\u00eetre tr\u00e8s t\u00f4t dans l&#8217;enfance, g\u00e9n\u00e9ralement vers 10 ans.<\/p>\n<p>Lors du premier examen, on r\u00e9alise des radiographies qui permettent de mesurer les angles de d\u00e9viation. Le traitement sera adapt\u00e9 en fonction du degr\u00e9 de d\u00e9viation. La scoliose est une maladie \u00e9volutive. C&#8217;est un peu avant la pubert\u00e9, juste avant l&#8217;apparition des premi\u00e8res r\u00e8gles, que la colonne commence sa phase de croissance rapide. C&#8217;est \u00e0 ce moment que l&#8217;on peut voir la scoliose s&#8217;aggraver. Une surveillance m\u00e9dicale fr\u00e9quente est alors n\u00e9cessaire chez les enfants \u00e0 risque. Le traitement propos\u00e9 sera de la kin\u00e9sith\u00e9rapie si l&#8217;\u00e9volution est nulle ou tr\u00e8s lente. Si on constate en 6 mois d&#8217;intervalle, une aggravation de quelques degr\u00e9s, on aura recours \u00e0 l&#8217;utilisation de corset sur mesure ou de pl\u00e2tres successifs. Le traitement peut durer plusieurs ann\u00e9es jusqu&#8217;\u00e0 la fin de la croissance. Si malgr\u00e9 le traitement, la d\u00e9viation s&#8217;accentue, entra\u00eenant des troubles cardiaques ou respiratoires, on a recours \u00e0 la chirurgie qui consiste \u00e0 r\u00e9duire la colonne et souder, par une arthrod\u00e8se, les vert\u00e8bres entre elles.<\/p>\n<\/div>\n<\/section>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mal de dos est une affection touchant &agrave; des degr&eacute;s divers &agrave; grand nombre de patients. On estime que 50 % de la population pr&eacute;sente un jour ou l&rsquo;autre un &eacute;pisode aigu de douleurs lombaires. On estime que le mal de dos est responsable de 10 % des incapacit&eacute;s de travail. Ces &eacute;pisodes sont heureusement transitoires mais dans 70% des cas ils sont le d&eacute;but de probl&egrave;mes chroniques.<\/p>\n","protected":false},"featured_media":4085,"parent":834,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"<p>Dans la plupart des cas, il s\u2019agit de blessures du disque intervert\u00e9bral, li\u00e9es \u00e0 son vieillissement naturel et ne repr\u00e9sente pas une maladie en tant que telle. La prise en charge de ces maux de dos chroniques est souvent complexe et n\u00e9cessite l\u2019implication de divers intervenants pour amener un soulagement au patient.<\/p>\n\n<p>La clinique du dos du CHU Saint-Pierre fait partie int\u00e9grante du service d\u2019orthop\u00e9die et se compose de kin\u00e9sith\u00e9rapeutes, ost\u00e9opathes, sophrologues, acupuncteurs, m\u00e9decin physique et chirurgiens. Une approche pluridisciplinaire permet ainsi d\u2019apporter une prise en charge personnalis\u00e9e pour chaque cas.<\/p>\n\n<p>L\u2019\u00e9quipe d\u2019orthop\u00e9die du CHU Saint-Pierre comprend plusieurs chirurgiens sp\u00e9cialis\u00e9s dans la chirurgie de la colonne. Parmi ceux-ci, il y a des membres de soci\u00e9t\u00e9s nationales et internationales de chirurgie de la colonne, auteurs de divers travaux scientifiques.<\/p>\n\n<p>Toutes les pathologies chirurgicales touchant la colonne sont prises en charge dans notre service qui travaille \u00e9galement en \u00e9troite collaboration avec le service de neurochirurgie et nous utilisons les techniques les plus modernes afin de garantir une prise en charge optimale.<\/p>\n\n<p>Outre les cas de tumeurs ou de fracture de la colonne, heureusement plus rares, les pathologies les plus souvent trait\u00e9es de fa\u00e7on chirurgicale sont le canal \u00e9troit lombaire, la hernie discale cervicale ou lombaire, la lombalgie primaire r\u00e9sistante au traitement m\u00e9dical.<\/p>\n\n<p>\u00a0<\/p>\n\n<p><b>G\u00e9n\u00e9ralit\u00e9s<\/b><\/p>\n\n<p>La colonne vert\u00e9brale ou rachis se d\u00e9compose en 4 zones, de haut en bas, en colonne cervicale (7 vert\u00e8bres), thoracique (12 vert\u00e8bres), lombaire (5 vert\u00e8bres) et sacr\u00e9e (5 vert\u00e8bres soud\u00e9es). Elle se termine par le coccyx. Dans le plan frontal, la colonne est rectiligne mais de profil, elle forme un S allong\u00e9. On parle de lordose cervicale, cyphose dorsale et lordose lombaire. Ses courbures sont physiologiques quand elles restent dans certaines limites et sont telles que la t\u00eate se situe au-dessus du bassin. On parle de colonne bien \u00e9quilibr\u00e9e.<\/p>\n\n<p><img alt=\"\" src=\"http:\/\/www.stpierre-bru.be\/images\/dos\/1.jpg\" \/><\/p>\n\n<p>La colonne a une fonction de soutien du corps mais \u00e9galement de protection de la moelle.<\/p>\n\n<p>Au niveau de chaque vert\u00e8bre, deux nerfs sortent de la colonne par les trous de conjugaison ou foramen, un \u00e0 gauche et un \u00e0 droite, pour innerver les muscles ou donner la sensibilit\u00e9 dans certains territoires de la peau. Chaque nerf a un territoire bien pr\u00e9cis. Les nerfs sortants au niveau des trois derni\u00e8res vert\u00e8bres lombaires se regroupent en un gros nerf, le nerf sciatique, puis se s\u00e9parent plus bas dans la jambe pour rejoindre leur territoire cutan\u00e9 sp\u00e9cifique. Par exemple, le nerf sortant entre la cinqui\u00e8me vert\u00e8bre lombaire et le sacrum, va donner la sensibilit\u00e9 au gros orteil. S\u2019il est bless\u00e9 lorsqu'il sort de la colonne, comme dans le cas d'une hernie discale, le patient aura mal au gros orteil. Ceci permet de diagnostiquer facilement par le seul interrogatoire du patient, l'endroit o\u00f9 a pu se faire la hernie discale.<\/p>\n\n<p>\u00a0<\/p>\n\n<p><b>Le canal lombaire \u00e9troit<\/b><\/p>\n\n<p>\u00c9tant li\u00e9e au remaniement de la colonne vert\u00e9brale avec l\u2019\u00e2ge et au vu de l\u2019augmentation de l\u2019esp\u00e9rance de vie, cette affection est de plus en plus fr\u00e9quente et touche des patients principalement de 70, 80 voire 90 ans. Il s\u2019agit de la diminution du calibre du canal rachidien. Dans ce canal, passe la moelle \u00e9pini\u00e8re dans les r\u00e9gions cervicale et dorsale. Au niveau de la colonne lombaire on y retrouve le sac dural qui contient les racines nerveuses qui donneront l\u2019innervation dans les jambes. La diminution du diam\u00e8tre canalaire est la plupart du temps une cons\u00e9quence du vieillissement de la colonne vert\u00e9brale. Il y a d\u2019une part le vieillissement des disques intervert\u00e9braux qui s\u2019\u00e9crasent et viennent faire une protrusion dans le canal rachidien et d\u2019autre part l\u2019arthrose des articulations qui les d\u00e9forment, les rendant de plus en plus volumineuses. La conjonction de ces deux ph\u00e9nom\u00e8nes entra\u00eene une compression du sac dural et par l\u00e0 m\u00eame de l\u2019ensemble des nerfs.<\/p>\n\n<p><img alt=\"\" height=\"226\" src=\"http:\/\/www.stpierre-bru.be\/images\/dos\/2.jpg\" width=\"220\" \/>\u00a0Canal normal \u00a0 \u00a0 \u00a0 \u00a0<img alt=\"\" height=\"226\" src=\"http:\/\/www.stpierre-bru.be\/images\/dos\/3.jpg\" \/>\u00a0canal \u00e9troit<\/p>\n\n<p>Les plaintes d\u00e9crites par un patient pr\u00e9sentant un canal lombaire \u00e9troit sont assez typiques. Outre les douleurs lombaires li\u00e9es aux ph\u00e9nom\u00e8nes d\u2019arthrose, le patient ressentira surtout des douleurs dans les cuisses et dans les jambes apparaissant \u00e0 la marche. La douleur apparait typiquement apr\u00e8s une certaine distance de marche l\u2019obligeant \u00e0 s\u2019arr\u00eater et \u00e0 s\u2019asseoir pour que la douleur s\u2019estompe. Apr\u00e8s quelques minutes, il peut reprendre son chemin mais apr\u00e8s la m\u00eame distance de marche, les douleurs r\u00e9appara\u00eetront l\u2019obligeant une nouvelle fois \u00e0 s\u2019arr\u00eater.<\/p>\n\n<p>Cette affection \u00e9volue lentement, ne repr\u00e9sente pas un danger mais devient g\u00eanante pour le patient qui voit sa distance de marche se r\u00e9duire avec le temps.<\/p>\n\n<p>La question souvent pos\u00e9e est de savoir s\u2019il faut op\u00e9rer un canal \u00e9troit. Il est rare que le patient pr\u00e9sente des troubles neurologiques graves \u00e9voluant rapidement. C\u2019est pour cela, que l\u2019op\u00e9ration n\u2019est quasi jamais urgente et que l\u2019on peut se permettre dans un premier temps de proposer des traitements m\u00e9dicaux, kin\u00e9sith\u00e9rapie voire m\u00eame des p\u00e9ridurales pour soulager le patient. En cas d\u2019\u00e9chec de ces traitements et de g\u00eanes suffisantes entra\u00eenant une d\u00e9t\u00e9rioration de la qualit\u00e9 de vie, une intervention peut \u00eatre propos\u00e9e. Bien s\u00fbr, en cas de perte de force, de sensibilit\u00e9 ou de contr\u00f4le des sphincters, l\u2019intervention s\u2019av\u00e8re urgente.<\/p>\n\n<p>La peur du patient est souvent le risque de paralysie lors d\u2019une intervention. Les complications possibles de l\u2019intervention vous seront expliqu\u00e9es par votre chirurgien lors de la consultation. Bien que le risque z\u00e9ro n\u2019existe pas, le but de l\u2019intervention \u00e9tant de redonner de l\u2019espace aux structures nerveuses, tout doit aller vers une situation en am\u00e9liorant la situation neurologique du patient. L\u2019intervention se fait par une incision dans le dos et consiste \u00e0 \u00ab gratter \u00bb l\u2019os pour redonner suffisamment d\u2019espace aux structures nerveuses. Parfois, on peut associer une arthrod\u00e8se c\u2019est-\u00e0-dire une fusion des vert\u00e8bres \u00e0 l\u2019aide de vis si une instabilit\u00e9 des vert\u00e8bres est mise en \u00e9vidence. Cet ajout de vis a tr\u00e8s peu de cons\u00e9quences sur la mobilit\u00e9 qui est d\u00e9j\u00e0 fort diminu\u00e9e dans une colonne vert\u00e9brale atteinte d\u2019un canal \u00e9troit.<\/p>\n\n<p>Apr\u00e8s l\u2019intervention, le patient est alit\u00e9 parfois 24 heures puis peut marcher avec l\u2019aide d\u2019un kin\u00e9sith\u00e9rapeute. La dur\u00e9e moyenne d\u2019hospitalisation est de cinq jours. G\u00e9n\u00e9ralement, le patient est apte \u00e0 retourner \u00e0 son domicile apr\u00e8s ce d\u00e9lai. S\u2019il est isol\u00e9 et pourrait pr\u00e9senter des difficult\u00e9s pour son retour \u00e0 domicile, un s\u00e9jour en revalidation est toujours envisageable.<\/p>\n\n<p>\u00a0<\/p>\n\n<p><b>La hernie discale<\/b><\/p>\n\n<p>Le disque vert\u00e9bral est compos\u00e9 de fibres de collag\u00e8ne concentriques autour du nuclleus pulposus. D\u00e8s 25 ans, des l\u00e9sions de ces fibres peuvent appara\u00eetre lors d'effort, comme soulever une charge, souvent pour des gestes de la vie courante. Des d\u00e9chirures surviennent entra\u00eenant la douleur. On parle de lumbago ou de lombalgie quand la douleur reste localis\u00e9e \u00e0 la colonne lombaire, cervicalgie au niveau cervical.<\/p>\n\n<p>Si la d\u00e9chirure est plus importante, le contenu du disque, le nucleus pulposus, peut s'\u00e9chapper dans le canal rachidien et cr\u00e9\u00e9 une hernie discale. La hernie peut \u00eatre centrale et comprimer le sac dural, ou, lat\u00e9rale et comprimer les racines. Il s'ensuit une douleur \u00e9lective dans un territoire de la jambe sp\u00e9cifique du nerf l\u00e9s\u00e9. On parle de sciatalgie pouvant \u00eatre associ\u00e9e \u00e0 une perte de sensibilit\u00e9 voire une paralysie.<\/p>\n\n<p><img alt=\"\" src=\"http:\/\/www.stpierre-bru.be\/images\/dos\/4.jpg\" \/>\u00a0Hernie lat\u00e9rale entra\u00eenant une compression de la racine nerveuse<\/p>\n\n<p>\u00a0<\/p>\n\n<p>Dans 80 % des cas, le traitement de la hernie discale ne n\u00e9cessite pas d\u2019op\u00e9ration. En cas d\u2019 hernie discale non paralysante, c\u2019est-\u00e0-dire n\u2019entra\u00eenant pas de troubles neurologiques graves, dans un premier temps, on commence toujours par un traitement conservateur par repos, anti-inflammatoires et relaxant musculaire. On peut \u00e9galement r\u00e9aliser une p\u00e9ridurale th\u00e9rapeutique. Il s'agit d'injecter de la cortisone localement afin de diminuer l'inflammation due \u00e0 la hernie. En cas d'\u00e9chec du traitement conservateur, on peut avoir recours \u00e0 la chirurgie, surtout lors de douleurs invalidantes. En cas de hernie discale paralysante ou s\u2019accompagnant d\u2019une anesth\u00e9sie, on a toujours recours \u00e0 une intervention chirurgicale en urgence.<\/p>\n\n<p>Le but de l\u2019intervention est d\u2019enlever la hernie et de cureter le disque pour \u00e9viter une r\u00e9cidive. Au niveau lombaire, le chirurgien incisera dans le dos en regard du disque ab\u00eem\u00e9. Gr\u00e2ce \u00e0 des instruments adapt\u00e9s, nous pouvons par microchirurgie r\u00e9aliser des incisions de moins de trois centim\u00e8tres pour aborder le disque malade. En \u00e9cartant prudemment le sac dural et la racine nerveuse,\u00a0 le chirurgien a acc\u00e8s \u00e0 la hernie et peut l\u2019\u00f4ter.<\/p>\n\n<p>Avec ce type d\u2019intervention, le patient peut g\u00e9n\u00e9ralement se lever le matin et sortir au deuxi\u00e8me ou troisi\u00e8me jour postop\u00e9ratoire.<\/p>\n\n<p>La hernie discale peut \u00e9galement \u00eatre pr\u00e9sente au niveau de la colonne cervicale. \u00c0 ce moment, le patient peut ressentir outre une douleur dans le cou, une douleur irradiante jusque dans les doigts. Les indications op\u00e9ratoires restent les m\u00eames que pour la r\u00e9gion lombaire. Dans la majorit\u00e9 des cas, le traitement est conservateur. Le patient b\u00e9n\u00e9ficie d\u2019anti-inflammatoires, de relaxants musculaires. Une p\u00e9ridurale cervicale peut \u00e9galement \u00eatre r\u00e9alis\u00e9e dans le cas de douleurs plus fortes. Le port d\u2019une minerve permet de mettre la r\u00e9gion cervicale au repos.\u00a0 L\u2019intervention est requise pour les douleurs invalidantes ne r\u00e9pondant pas au traitement classique ou en cas de d\u00e9ficit neurologique.<\/p>\n\n<p>\u00a0<\/p>\n\n<p><b>Arthrose lombaire et discopathies d\u00e9g\u00e9n\u00e9ratives<\/b><\/p>\n\n<p>L'arthrose de la colonne lombaire touche le plus fr\u00e9quemment les vert\u00e8bres L4, L5 et S1.\u00a0 Les douleurs occasionn\u00e9es par l'arthrose s'appellent des lombalgies.\u00a0 Elles sont dues \u00e0 l'usure du cartilage situ\u00e9 sur les facettes articulaires des vert\u00e8bres ou \u00e0 l\u2019usure des disques intervert\u00e9braux. On parlera dans ce dernier cas de discopathie.<\/p>\n\n<p>Le traitement sera m\u00e9dical mais se fera \u00e9galement via le repos, la kin\u00e9sith\u00e9rapie, l\u2019ost\u00e9opathie, l\u2019acupuncture, la physioth\u00e9rapie parfois m\u00eame par le psychologue en cas de douleur chronique associ\u00e9e \u00e0 un stress ou par un anesth\u00e9siste pour des d\u00e9sensibilisations. En cas de douleurs non soulag\u00e9es par le traitement m\u00e9dical, un blocage de deux ou plusieurs vert\u00e8bres par\u00a0 arthrod\u00e8se peut \u00eatre envisag\u00e9.\u00a0 Celui-ci se fait \u00e0 l'aide de plaques et de vis fixant les vert\u00e8bres malades entre elles.<\/p>\n\n<p>\u00a0<\/p>\n\n<p><img alt=\"\" src=\"http:\/\/www.stpierre-bru.be\/images\/dos\/7.jpg\" \/><\/p>\n\n<p>Cette intervention doit cependant rester exceptionnelle. En effet bon nombre de patients garde des douleurs apr\u00e8s l\u2019op\u00e9ration et on estime que seulement 70 % sont soulag\u00e9s apr\u00e8s la chirurgie et que seuls 20 \u00e0 30 % n\u2019ont plus de douleur. Ceci veut \u00e9galement dire que 30 % des patients ont gard\u00e9 des douleurs similaires voire plus importantes apr\u00e8s l\u2019intervention. On r\u00e9serve donc la chirurgie lorsqu\u2019 aucun autre traitement n\u2019a pu soulager le patient et que la douleur reste fortement invalidante, entravant la qualit\u00e9 de vie du patient.<\/p>\n\n<p>\u00a0<\/p>\n\n<p><b>La scoliose<\/b><\/p>\n\n<p>Parmi les d\u00e9formations de la colonne vert\u00e9brale, la plus connue touchant l\u2019enfant est la scoliose. C\u2019est une d\u00e9formation compliqu\u00e9e de la colonne qui lui donne de face un aspect de S allong\u00e9. La d\u00e9viation peut se situer n'importe o\u00f9 sur la colonne. On parle de scoliose thoracique, thoraco-lombaire ou lombaire en fonction de l'endroit de la d\u00e9viation. Quand la maladie est situ\u00e9e au niveau thoracique et est tr\u00e8s \u00e9volu\u00e9e, les vert\u00e8bres qui pivotent, repoussent vers l'arri\u00e8re les c\u00f4tes situ\u00e9es du cot\u00e9 convexe de la courbure cr\u00e9ant une bosse ou une gibbosit\u00e9, qui se voit encore mieux lorsque le sujet se penche en avant.<\/p>\n\n<p><img alt=\"\" src=\"http:\/\/www.stpierre-bru.be\/images\/dos\/5.jpg\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img alt=\"\" src=\"http:\/\/www.stpierre-bru.be\/images\/dos\/6.jpg\" \/><\/p>\n\n<p>La scoliose vraie est une d\u00e9formation irr\u00e9ductible et ne doit pas \u00eatre confondue avec une attitude scoliotique qui peut \u00eatre due \u00e0 un mauvais maintien d\u2019un patient debout, ou une scoliose compensatoire qui est une d\u00e9viation li\u00e9e \u00e0 une diff\u00e9rence de longueur de membres. Ces deux scolioses disparaissent en position couch\u00e9e.<\/p>\n\n<p>Devant une scoliose irr\u00e9ductible, on recherche toujours une cause neurologique ou cong\u00e9nitale mais dans plus de 70% des cas aucune cause ne sera retrouv\u00e9e. On parle alors de scoliose idiopathique. La scoliose idiopathique se rencontre 7 fois plus souvent chez les filles et peut appara\u00eetre tr\u00e8s t\u00f4t dans l'enfance, g\u00e9n\u00e9ralement vers 10 ans.<\/p>\n\n<p>Lors du premier examen, on r\u00e9alise des radiographies qui permettent de mesurer les angles de d\u00e9viation. Le traitement sera adapt\u00e9 en fonction du degr\u00e9 de d\u00e9viation. La scoliose est une maladie \u00e9volutive. C'est un peu avant la pubert\u00e9, juste avant l'apparition des premi\u00e8res r\u00e8gles, que la colonne commence sa phase de croissance rapide. C'est \u00e0 ce moment que l'on peut voir la scoliose s'aggraver. Une surveillance m\u00e9dicale fr\u00e9quente est alors n\u00e9cessaire chez les enfants \u00e0 risque. Le traitement propos\u00e9 sera de la kin\u00e9sith\u00e9rapie si l'\u00e9volution est nulle ou tr\u00e8s lente. Si on constate en 6 mois d'intervalle, une aggravation de quelques degr\u00e9s, on aura recours \u00e0 l'utilisation de corset sur mesure ou de pl\u00e2tres successifs. Le traitement peut durer plusieurs ann\u00e9es jusqu'\u00e0 la fin de la croissance. Si malgr\u00e9 le traitement, la d\u00e9viation s'accentue, entra\u00eenant des troubles cardiaques ou respiratoires, on a recours \u00e0 la chirurgie qui consiste \u00e0 r\u00e9duire la colonne et souder, par une arthrod\u00e8se, les vert\u00e8bres entre elles.<\/p>\n","_et_gb_content_width":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"categories":[1869,44],"tags":[329,326,322,62,317,285,319,327,323,314,321,315,316,325,318,324,312,328,330,320,313],"class_list":["post-1012","service","type-service","status-publish","has-post-thumbnail","hentry","category-orthopedie-traumatologie","category-specialite","tag-acupuncture","tag-arthrose-lombaire","tag-canal-rachidien","tag-chirurgie","tag-coccyx","tag-colonne-vertebrale","tag-cyphose-dorsale","tag-discopathies-degeneratives","tag-disque-vertebrale","tag-dorsales","tag-hernie-discale","tag-kine","tag-kinesitherapeute","tag-lombalgie","tag-lordose-lombaire","tag-lumbago","tag-moelle","tag-osteopathie","tag-physiotherapie","tag-scoliose","tag-vertebres"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chirurgie de la colonne vert\u00e9brale - CHU Saint-Pierre | UMC Sint-Pieter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chirurgie de la colonne vert\u00e9brale - CHU Saint-Pierre | UMC Sint-Pieter\" \/>\n<meta property=\"og:description\" content=\"Le mal de dos est une affection touchant &agrave; des degr&eacute;s divers &agrave; grand nombre de patients. On estime que 50 % de la population pr&eacute;sente un jour ou l&rsquo;autre un &eacute;pisode aigu de douleurs lombaires. On estime que le mal de dos est responsable de 10 % des incapacit&eacute;s de travail. Ces &eacute;pisodes sont heureusement transitoires mais dans 70% des cas ils sont le d&eacute;but de probl&egrave;mes chroniques.\" \/>\n<meta property=\"og:site_name\" content=\"CHU Saint-Pierre | UMC Sint-Pieter\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-27T19:55:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.stpierre-bru.be\/wp-content\/uploads\/2021\/11\/Orthopedie_genou_hache_epaule_main_dos.png?fit=850%2C748&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/orthopedie-traumatologie\\\/chirurgie-de-la-colonne-vertebrale\\\/\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/orthopedie-traumatologie\\\/chirurgie-de-la-colonne-vertebrale\\\/\",\"name\":\"Chirurgie de la colonne vert\u00e9brale - CHU Saint-Pierre | UMC Sint-Pieter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/orthopedie-traumatologie\\\/chirurgie-de-la-colonne-vertebrale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/orthopedie-traumatologie\\\/chirurgie-de-la-colonne-vertebrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stpierre-bru.be\\\/app\\\/uploads\\\/2021\\\/11\\\/Orthopedie_genou_hache_epaule_main_dos.png\",\"datePublished\":\"2021-11-14T21:25:10+00:00\",\"dateModified\":\"2022-03-27T19:55:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/orthopedie-traumatologie\\\/chirurgie-de-la-colonne-vertebrale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/orthopedie-traumatologie\\\/chirurgie-de-la-colonne-vertebrale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/orthopedie-traumatologie\\\/chirurgie-de-la-colonne-vertebrale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/app\\\/uploads\\\/2021\\\/11\\\/Orthopedie_genou_hache_epaule_main_dos.png\",\"contentUrl\":\"https:\\\/\\\/www.stpierre-bru.be\\\/app\\\/uploads\\\/2021\\\/11\\\/Orthopedie_genou_hache_epaule_main_dos.png\",\"width\":850,\"height\":748,\"caption\":\"Orthop\u00e9die, genou, hanche, main, \u00e9paule\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/orthopedie-traumatologie\\\/chirurgie-de-la-colonne-vertebrale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stpierre-bru.be\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/www.stpierre-bru.be\\\/nos-services-de-consultation\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Orthop\u00e9die Traumatologie\",\"item\":\"https:\\\/\\\/www.stpierre-bru.be\\\/service\\\/orthopedie-traumatologie\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Chirurgie de la colonne vert\u00e9brale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#website\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/\",\"name\":\"CHU Saint-Pierre | UMC Sint-Pieter\",\"description\":\"Bienvenue\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stpierre-bru.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#organization\",\"name\":\"CHU Saint-Pierre | UMC Sint-Pieter\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stpierre-bru.be\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo_chu_umc_0.png\",\"contentUrl\":\"https:\\\/\\\/www.stpierre-bru.be\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo_chu_umc_0.png\",\"width\":733,\"height\":281,\"caption\":\"CHU Saint-Pierre | UMC Sint-Pieter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stpierre-bru.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chirurgie de la colonne vert\u00e9brale - CHU Saint-Pierre | UMC Sint-Pieter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/","og_locale":"en_US","og_type":"article","og_title":"Chirurgie de la colonne vert\u00e9brale - CHU Saint-Pierre | UMC Sint-Pieter","og_description":"Le mal de dos est une affection touchant &agrave; des degr&eacute;s divers &agrave; grand nombre de patients. On estime que 50 % de la population pr&eacute;sente un jour ou l&rsquo;autre un &eacute;pisode aigu de douleurs lombaires. On estime que le mal de dos est responsable de 10 % des incapacit&eacute;s de travail. Ces &eacute;pisodes sont heureusement transitoires mais dans 70% des cas ils sont le d&eacute;but de probl&egrave;mes chroniques.","og_site_name":"CHU Saint-Pierre | UMC Sint-Pieter","article_modified_time":"2022-03-27T19:55:48+00:00","og_image":[{"width":850,"height":748,"url":"https:\/\/i0.wp.com\/www.stpierre-bru.be\/wp-content\/uploads\/2021\/11\/Orthopedie_genou_hache_epaule_main_dos.png?fit=850%2C748&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/","url":"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/","name":"Chirurgie de la colonne vert\u00e9brale - CHU Saint-Pierre | UMC Sint-Pieter","isPartOf":{"@id":"https:\/\/www.stpierre-bru.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/#primaryimage"},"image":{"@id":"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2021\/11\/Orthopedie_genou_hache_epaule_main_dos.png","datePublished":"2021-11-14T21:25:10+00:00","dateModified":"2022-03-27T19:55:48+00:00","breadcrumb":{"@id":"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/#primaryimage","url":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2021\/11\/Orthopedie_genou_hache_epaule_main_dos.png","contentUrl":"https:\/\/www.stpierre-bru.be\/app\/uploads\/2021\/11\/Orthopedie_genou_hache_epaule_main_dos.png","width":850,"height":748,"caption":"Orthop\u00e9die, genou, hanche, main, \u00e9paule"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/chirurgie-de-la-colonne-vertebrale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stpierre-bru.be\/en\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/www.stpierre-bru.be\/nos-services-de-consultation\/"},{"@type":"ListItem","position":3,"name":"Orthop\u00e9die Traumatologie","item":"https:\/\/www.stpierre-bru.be\/service\/orthopedie-traumatologie\/"},{"@type":"ListItem","position":4,"name":"Chirurgie de la colonne vert\u00e9brale"}]},{"@type":"WebSite","@id":"https:\/\/www.stpierre-bru.be\/#website","url":"https:\/\/www.stpierre-bru.be\/","name":"CHU Saint-Pierre | UMC Sint-Pieter","description":"Bienvenue","publisher":{"@id":"https:\/\/www.stpierre-bru.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stpierre-bru.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.stpierre-bru.be\/#organization","name":"CHU Saint-Pierre | UMC Sint-Pieter","url":"https:\/\/www.stpierre-bru.be\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.stpierre-bru.be\/#\/schema\/logo\/image\/","url":"https:\/\/www.stpierre-bru.be\/wp-content\/uploads\/2021\/06\/Logo_chu_umc_0.png","contentUrl":"https:\/\/www.stpierre-bru.be\/wp-content\/uploads\/2021\/06\/Logo_chu_umc_0.png","width":733,"height":281,"caption":"CHU Saint-Pierre | UMC Sint-Pieter"},"image":{"@id":"https:\/\/www.stpierre-bru.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/service\/1012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/types\/service"}],"up":[{"embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/service\/834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/media\/4085"}],"wp:attachment":[{"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/media?parent=1012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/categories?post=1012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stpierre-bru.be\/en\/wp-json\/wp\/v2\/tags?post=1012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}